{"id":973,"date":"2025-04-03T14:15:22","date_gmt":"2025-04-03T20:15:22","guid":{"rendered":"https:\/\/lacomarcadelostalentos.com\/lct\/?post_type=product&#038;p=973"},"modified":"2025-06-24T18:11:15","modified_gmt":"2025-06-25T00:11:15","slug":"test-lct-jovenes","status":"publish","type":"product","link":"https:\/\/lacomarcadelostalentos.com\/lct\/producto\/test-lct-jovenes\/","title":{"rendered":"Test LCT Jovenes"},"content":{"rendered":"<p>Te invito a tomes el curso \u201cDespierta la Genialidad de tus hijos\u201d (totalmente en l\u00ednea).<\/p>\n<p>Seis m\u00f3dulos, en donde se abordar\u00e1n los siguientes temas:<br \/>\n&#8211; La cultura del merecimiento.<br \/>\n&#8211; Tipos de padres.<br \/>\n&#8211; Lo que un padre nunca deber\u00eda decirle a un hijo.<br \/>\n&#8211; Las tres herramientas fundamentales para encontrar una vocaci\u00f3n.<br \/>\n&#8211; \u00bfQu\u00e9 tanto te conoces a ti mismo?<br \/>\n&#8211; La vocaci\u00f3n<br \/>\n&#8211; La genialidad.<br \/>\n&#8211; \u00bfQu\u00e9 buscamos cuando queremos ser padres?<br \/>\n&#8211; Carta a mi hijo.<br \/>\n&#8211; El poder de las palabras.<br \/>\n&#8211; La escucha emp\u00e1tica.<br \/>\n&#8211; Encuentra tu PPV (Prop\u00f3sito Personal de vida)<br \/>\n&#8211; Adopta a tus hijos.<br \/>\nTodos los videos son impartidos por el Dr. \u00c1ngel de Luna.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xdj266r x126k92a\">\n<div dir=\"auto\">\u00bfQu\u00e9 tipo de padre eres?<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\u00bfTe genera tensi\u00f3n o incertidumbre el futuro de tus hijos?<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\u00bfEres un padre realmente interesado en el desarrollo arm\u00f3nico de tus hijos?<\/div>\n<\/div>\n","protected":false},"featured_media":1143,"template":"","meta":[],"product_brand":[],"product_cat":[23],"product_tag":[],"class_list":["post-973","product","type-product","status-publish","has-post-thumbnail","product_cat-test","first","instock","downloadable","virtual","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/lacomarcadelostalentos.com\/lct\/wp-json\/wp\/v2\/product\/973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacomarcadelostalentos.com\/lct\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lacomarcadelostalentos.com\/lct\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacomarcadelostalentos.com\/lct\/wp-json\/wp\/v2\/media\/1143"}],"wp:attachment":[{"href":"https:\/\/lacomarcadelostalentos.com\/lct\/wp-json\/wp\/v2\/media?parent=973"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lacomarcadelostalentos.com\/lct\/wp-json\/wp\/v2\/product_brand?post=973"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lacomarcadelostalentos.com\/lct\/wp-json\/wp\/v2\/product_cat?post=973"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lacomarcadelostalentos.com\/lct\/wp-json\/wp\/v2\/product_tag?post=973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}